{"id":487,"date":"2022-09-12T01:41:59","date_gmt":"2022-09-12T01:41:59","guid":{"rendered":"https:\/\/osgeraldos.com.br\/?p=487"},"modified":"2023-12-30T17:47:29","modified_gmt":"2023-12-30T17:47:29","slug":"incubadora","status":"publish","type":"post","link":"https:\/\/osgeraldos.com.br\/es\/incubadora\/","title":{"rendered":"Incubadora de Grupos Art\u00edsticos"},"content":{"rendered":"<div id=\"fws_6a04ebfb8ee05\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row full-width-content vc_row-o-equal-height vc_row-flex vc_row-o-content-middle\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-overlay=\"false\"><div class=\"inner-wrap\"><div class=\"row-bg viewport-desktop using-bg-color\"  style=\"background-color: #222222; \"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div style=\"\" class=\"vc_col-sm-6 wpb_column column_container vc_column_container col has-animation no-extra-padding inherit_tablet inherit_phone\" data-using-bg=\"true\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"reveal-from-right\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-image-bg-wrap column-bg-layer viewport-desktop\" data-n-parallax-bg=\"true\" data-parallax-speed=\"minimum\" data-bg-pos=\"center bottom\" data-bg-animation=\"none\" data-bg-overlay=\"false\"><div class=\"inner-wrap\"><div class=\"column-image-bg parallax-layer\" style=\" background-image: url('https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/10\/encontros-de-gestao-Incubadora-Tatui-2017.jpg'); \"><\/div><\/div><\/div>\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 500px;\" class=\"divider\"><\/div><\/div><div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 5px;\" class=\"divider\"><\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div style=\"\" class=\"vc_col-sm-6 wpb_column column_container vc_column_container col centered-text padding-7-percent inherit_tablet inherit_phone\" data-using-bg=\"true\" data-padding-pos=\"all\" data-has-bg-color=\"true\" data-bg-color=\"#ffffff\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap column-bg-layer\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\" style=\"opacity: 1; background-color: #ffffff;\"><\/div><\/div>\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n<div class=\"wpb_text_column wpb_content_element  vc_custom_1662414087192\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<p><span style=\"font-weight: 400;\">La Incubadora de Grupos Art\u00edsticos es un proyecto amplio de Formaci\u00f3n, Capacitaci\u00f3n y Consultor\u00eda en Gesti\u00f3n Cultural, dirigido a artistas de todas las disciplinas, ya sea en colectivo o en carrera individual. Este proceso formativo desarrolla habilidades, herramientas y metodolog\u00edas que mejoran la estructura de gesti\u00f3n, tambi\u00e9n favorecen la sostenibilidad y constancia de las iniciativas art\u00edsticas de los participantes. Desde su primera edici\u00f3n en 2017, las acciones pedag\u00f3gicas se llevaron a cabo de manera presencial para 118 artistas y 40 grupos del interior de S\u00e3o Paulo que, mediante el abordaje pr\u00e1ctico del contenido pedag\u00f3gico, hicieron realidad proyectos culturales de exposiciones art\u00edsticas, cortometrajes, exhibiciones de fotos y presentaciones de espect\u00e1culos teatrales, multiplicando los impactos de la Incubadora en las regiones por donde pas\u00f3.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Adem\u00e1s de la formaci\u00f3n en Gesti\u00f3n Cultural, que constituye la base estructural del proyecto, tambi\u00e9n se realizaron acciones de Difusi\u00f3n Cultural y Formaci\u00f3n de P\u00fablico en todas las ediciones, esto ampli\u00f3 la red de relaciones con el p\u00fablico en general y alcanz\u00f3 cerca de 2000 personas, a trav\u00e9s de presentaciones art\u00edsticas. As\u00ed, todos los involucrados en este proceso pedag\u00f3gico, tanto j\u00f3venes artistas\/grupos como profesores, pudieron sentir la experiencia del encuentro y del acontecimiento po\u00e9tico, que son la causa y el efecto del cultivo de la inspiraci\u00f3n y la imaginaci\u00f3n, pero tambi\u00e9n de todo el trabajo apol\u00edneo y terrestre involucrado en las \u00e1reas de la Gesti\u00f3n Cultural.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En nuestra edici\u00f3n m\u00e1s reciente, realizada en 2021 bajo contexto pand\u00e9mico, la palabra \"virtual\", agregada al t\u00edtulo, indica, en su sentido m\u00e1s com\u00fan, la realizaci\u00f3n en formato digital, lo que permiti\u00f3 la expansi\u00f3n del proyecto para artistas y gestores de todo el pa\u00eds. Adem\u00e1s, refuerza el car\u00e1cter del proyecto a trav\u00e9s del sentido original del t\u00e9rmino: \"virtual\" proviene del lat\u00edn medieval \"Virtuale\" o \"Virtualis\", que significa virtud, fuerza y potencia. Representa, por lo tanto, la inspiraci\u00f3n y el fortalecimiento de proyectos art\u00edsticos.<\/span><\/p>\n\t<\/div>\n<\/div>\n\n\n\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a04ebfb8f1e2\"  data-column-margin=\"default\" data-midnight=\"dark\" data-top-percent=\"5%\" data-bottom-percent=\"5%\"  class=\"wpb_row vc_row-fluid vc_row full-width-content vc_row-o-equal-height vc_row-flex vc_row-o-content-top  nectar-overflow-hidden\"  style=\"padding-top: calc(100vw * 0.05); padding-bottom: calc(100vw * 0.05); \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-overlay=\"false\"><div class=\"inner-wrap\"><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding el_spacing_0px inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div id=\"fws_6a04ebfb8f2bf\" data-midnight=\"\" data-column-margin=\"none\" class=\"wpb_row vc_row-fluid vc_row inner_row\"  style=\" z-index: 100;\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" data-scroll-animation=\"true\" data-scroll-animation-movement=\"transform_x\" data-scroll-animation-mobile=\"true\" data-scroll-animation-intensity=\"3.5\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar-scrolling-text font_size_11vw font_size_mobile_15vw\" data-style=\"text_outline\" data-s-dir=\"ltr\" data-spacing=\"false\" data-outline-thickness=\"ultra-thin\" data-s-speed=\"slowest\" data-overflow=\"visible\" ><div class=\"nectar-scrolling-text-inner\" style=\"color: #d6b176;\">\n<h1><em>formaci\u00f3n <\/em>formaci\u00f3n<span>&nbsp;<\/span><\/h1>\n\n<h1><em>formaci\u00f3n <\/em>formaci\u00f3n<span>&nbsp;<\/span><\/h1>\n\n<h1><em>formaci\u00f3n <\/em>formaci\u00f3n<span>&nbsp;<\/span><\/h1>\n\n<h1><em>formaci\u00f3n <\/em>formaci\u00f3n<span>&nbsp;<\/span><\/h1>\n\n<h1><em>formaci\u00f3n <\/em>formaci\u00f3n<span>&nbsp;<\/span><\/h1>\n<\/div><\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a04ebfb8f3f2\"  data-column-margin=\"default\" data-midnight=\"dark\" data-bottom-percent=\"7%\"  class=\"wpb_row vc_row-fluid vc_row full-width-content vc_row-o-equal-height vc_row-flex vc_row-o-content-top\"  style=\"padding-top: 0px; padding-bottom: calc(100vw * 0.07); \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-overlay=\"false\"><div class=\"inner-wrap\"><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t<div class=\"wpb_gallery wpb_content_element clearfix\">\n\t\t<div class=\"wpb_wrapper\"><div class=\"wpb_gallery_slidesflickity_static_height_style\" data-onclick=\"link_no\" data-interval=\"5\"><style>.wpb_gallery_slidesflickity_static_height_style .nectar-flickity.instace-6a04ebfb8f4bc:not(.masonry) .flickity-slider .cell img {\n      height: 400px;\n    }\n    @media only screen and (max-width: 1300px) {\n      .wpb_gallery_slidesflickity_static_height_style .nectar-flickity.instace-6a04ebfb8f4bc:not(.masonry) .flickity-slider .cell img {\n        height: 400px;\n      }\n    }\n    @media only screen and (max-width: 1000px) {\n      .wpb_gallery_slidesflickity_static_height_style .nectar-flickity.instace-6a04ebfb8f4bc:not(.masonry) .flickity-slider .cell img {\n        height: 350px;\n      }\n    }\n    @media only screen and (max-width: 690px) {\n      .wpb_gallery_slidesflickity_static_height_style .nectar-flickity.instace-6a04ebfb8f4bc:not(.masonry) .flickity-slider .cell img {\n        height: 300px;\n      }\n    }<\/style><div class=\"nectar-flickity not-initialized instace-6a04ebfb8f4bc\"  data-touch-icon-color=\"default\" data-drag-scale=\"\" data-overflow=\"hidden\" data-wrap=\"wrap\" data-spacing=\"default\" data-shadow=\"large_depth\" data-autoplay=\"\" data-autoplay-dur=\"\" data-free-scroll=\"\" data-controls=\"material_pagination\"><div class=\"flickity-viewport\"> <div class=\"flickity-slider\"><div class=\"cell\" data-lazy=\"false\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/10\/IMG-20180830-WA0032-1024x768.jpg\" class=\"skip-lazy nectar-lazy attachment-large\" alt=\"\" srcset=\"https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/10\/IMG-20180830-WA0032-1024x768.jpg 1024w, https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/10\/IMG-20180830-WA0032-300x225.jpg 300w, https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/10\/IMG-20180830-WA0032-768x576.jpg 768w, https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/10\/IMG-20180830-WA0032.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/div><div class=\"cell\" data-lazy=\"false\"><img decoding=\"async\" width=\"1\" height=\"1\" src=\"https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/10\/encontros-de-gestao-Incubadora-Tatui-2017.jpg\" class=\"skip-lazy nectar-lazy attachment-large\" alt=\"\" \/><\/div><div class=\"cell\" data-lazy=\"false\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/10\/encontro-de-gestao-1024x768.jpg\" class=\"skip-lazy nectar-lazy attachment-large\" alt=\"\" srcset=\"https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/10\/encontro-de-gestao-1024x768.jpg 1024w, https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/10\/encontro-de-gestao-300x225.jpg 300w, https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/10\/encontro-de-gestao-768x576.jpg 768w, https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/10\/encontro-de-gestao-1536x1152.jpg 1536w, https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/10\/encontro-de-gestao-2048x1536.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/div><div class=\"cell\" data-lazy=\"false\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/10\/encontros-de-gestao-abertura-Curso-de-Formacao-de-Atores-1024x576.jpg\" class=\"skip-lazy nectar-lazy attachment-large\" alt=\"\" srcset=\"https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/10\/encontros-de-gestao-abertura-Curso-de-Formacao-de-Atores-1024x576.jpg 1024w, https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/10\/encontros-de-gestao-abertura-Curso-de-Formacao-de-Atores-300x169.jpg 300w, https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/10\/encontros-de-gestao-abertura-Curso-de-Formacao-de-Atores-768x432.jpg 768w, https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/10\/encontros-de-gestao-abertura-Curso-de-Formacao-de-Atores-1536x864.jpg 1536w, https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/10\/encontros-de-gestao-abertura-Curso-de-Formacao-de-Atores-2048x1151.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/div><\/div><\/div>\n\t\t<\/div> \n\t<\/div> \n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>","protected":false},"excerpt":{"rendered":"Incubadora de Grupos Art\u00edsticos \u00e9 um projeto amplo de Forma\u00e7\u00e3o, Capacita\u00e7\u00e3o e Consultoria em Gest\u00e3o Cultural, direcionado a artistas de todas as linguagens, de coletivos ou em carreira solo. Esse...","protected":false},"author":1,"featured_media":705,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":{"0":"post-487","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-formacao"},"_links":{"self":[{"href":"https:\/\/osgeraldos.com.br\/es\/wp-json\/wp\/v2\/posts\/487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/osgeraldos.com.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/osgeraldos.com.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/osgeraldos.com.br\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/osgeraldos.com.br\/es\/wp-json\/wp\/v2\/comments?post=487"}],"version-history":[{"count":9,"href":"https:\/\/osgeraldos.com.br\/es\/wp-json\/wp\/v2\/posts\/487\/revisions"}],"predecessor-version":[{"id":834,"href":"https:\/\/osgeraldos.com.br\/es\/wp-json\/wp\/v2\/posts\/487\/revisions\/834"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/osgeraldos.com.br\/es\/wp-json\/wp\/v2\/media\/705"}],"wp:attachment":[{"href":"https:\/\/osgeraldos.com.br\/es\/wp-json\/wp\/v2\/media?parent=487"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/osgeraldos.com.br\/es\/wp-json\/wp\/v2\/categories?post=487"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/osgeraldos.com.br\/es\/wp-json\/wp\/v2\/tags?post=487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}