{"id":320,"date":"2022-04-24T13:46:22","date_gmt":"2022-04-24T13:46:22","guid":{"rendered":"https:\/\/osgeraldos.com.br\/?p=320"},"modified":"2023-02-01T18:51:15","modified_gmt":"2023-02-01T18:51:15","slug":"as-estrelas-do-ceu","status":"publish","type":"post","link":"https:\/\/osgeraldos.com.br\/es\/as-estrelas-do-ceu\/","title":{"rendered":"LAS ESTRELLAS DEL CIELO"},"content":{"rendered":"<div id=\"fws_6a04ebf26ba7e\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row full-width-content vc_row-o-equal-height vc_row-flex vc_row-o-content-middle\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-overlay=\"false\"><div class=\"inner-wrap\"><div class=\"row-bg viewport-desktop using-bg-color\"  style=\"background-color: #222222; \"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div style=\" color: #ffffff;\" class=\"vc_col-sm-6 wpb_column column_container vc_column_container col padding-10-percent inherit_tablet inherit_phone\" data-cfc=\"true\" data-using-bg=\"true\" data-padding-pos=\"all\" data-has-bg-color=\"true\" data-bg-color=\"#da5143\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap column-bg-layer\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\" style=\"opacity: 1; background-color: #da5143;\"><\/div><\/div>\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<h3><b>Sinopsis<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">En \"Las Estrellas del Cielo\", seguimos las aventuras de una ni\u00f1a que emprende un viaje fant\u00e1stico en busca de su gran sue\u00f1o: tocar las estrellas del cielo. Durante su larga traves\u00eda, recorrer\u00e1 lugares desconocidos y encontrar\u00e1 personajes incre\u00edbles que la ayudar\u00e1n a superar obst\u00e1culos y le mostrar\u00e1n los caminos que conducen a la \"escalera sin pelda\u00f1os\", el \u00fanico medio posible para alcanzar las estrellas. Inspirada en un antiguo cuento ingl\u00e9s, la obra nos recuerda que, para lograr un gran objetivo, debemos esforzarnos cada vez m\u00e1s.<\/span><\/p>\n<p><strong>Duraci\u00f3n:<\/strong> 60min<\/p>\n<p><span style=\"font-weight: 400;\"><strong>Clasificaci\u00f3n: <\/strong>todo p\u00fablico<\/span><\/p>\n\t<\/div>\n<\/div>\n\n\n\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div style=\"\" class=\"vc_col-sm-6 wpb_column column_container vc_column_container col has-animation no-extra-padding inherit_tablet inherit_phone\" data-using-bg=\"true\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"reveal-from-left\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-image-bg-wrap column-bg-layer viewport-desktop\" data-n-parallax-bg=\"true\" data-parallax-speed=\"minimum\" data-bg-pos=\"center center\" data-bg-animation=\"none\" data-bg-overlay=\"false\"><div class=\"inner-wrap\"><div class=\"column-image-bg parallax-layer\" style=\" background-image: url('https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/estrelasceu1.jpeg'); \"><\/div><\/div><\/div>\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a04ebf26c99d\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row full-width-content vc_row-o-equal-height vc_row-flex vc_row-o-content-top\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-overlay=\"false\"><div class=\"inner-wrap\"><div class=\"row-bg viewport-desktop using-bg-color\"  style=\"background-color: #222222; \"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div style=\"\" class=\"vc_col-sm-6 wpb_column column_container vc_column_container col has-animation no-extra-padding inherit_tablet inherit_phone\" data-using-bg=\"true\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"reveal-from-right\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-image-bg-wrap column-bg-layer viewport-desktop\" data-n-parallax-bg=\"true\" data-parallax-speed=\"minimum\" data-bg-pos=\"center center\" data-bg-animation=\"none\" data-bg-overlay=\"false\"><div class=\"inner-wrap\"><div class=\"column-image-bg parallax-layer\" style=\" background-image: url('https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/estrelasceu3.jpeg'); \"><\/div><\/div><\/div>\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div style=\"\" class=\"vc_col-sm-6 wpb_column column_container vc_column_container col padding-10-percent inherit_tablet inherit_phone\" data-using-bg=\"true\" data-padding-pos=\"all\" data-has-bg-color=\"true\" data-bg-color=\"#ffffff\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap column-bg-layer\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\" style=\"opacity: 1; background-color: #ffffff;\"><\/div><\/div>\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"nectar-split-heading\" data-align=\"default\" data-m-align=\"inherit\" data-text-effect=\"default\" data-animation-type=\"line-reveal-by-space\" data-animation-delay=\"0\" data-animation-offset=\"\" data-m-rm-animation=\"\" data-stagger=\"true\" data-custom-font-size=\"false\" ><h2 >Breve Historia<\/h2><\/div><div id=\"fws_6a04ebf26d15c\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col child_column has-animation no-extra-padding inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"fade-in-from-bottom\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<p><span style=\"font-weight: 400;\">El espect\u00e1culo se estren\u00f3 en 2017 en el SESC Campinas, despu\u00e9s de realizar ensayos abiertos en el CIS Guanabara, tambi\u00e9n en Campinas, y el preestreno en el Teatro Proc\u00f3pio Ferreira, en Tatu\u00ed. Al a\u00f1o siguiente, realiz\u00f3 una temporada en el Teatro de Arte y Oficio (Campinas) y particip\u00f3 en los festivales Festival de Teatro de Limeira, FESTIVALE en S\u00e3o Jos\u00e9 dos Campos y FESTE en Pindamonhangaba.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En 2019, se present\u00f3 en la Mostra de Artes C\u00eanicas de Indaiatuba para una audiencia de m\u00e1s de 600 personas, adem\u00e1s de funciones en el Auditorio de la C\u00e1mara de Valinhos y en el SESC Campinas.<\/span><\/p>\n\t<\/div>\n<\/div>\n\n\n\n\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a04ebf26d59a\"  data-column-margin=\"default\" data-midnight=\"dark\" data-bottom-percent=\"7%\"  class=\"wpb_row vc_row-fluid vc_row full-width-content vc_row-o-equal-height vc_row-flex vc_row-o-content-top\"  style=\"padding-top: 0px; padding-bottom: calc(100vw * 0.07); \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-overlay=\"false\"><div class=\"inner-wrap\"><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t<div class=\"wpb_gallery wpb_content_element clearfix\">\n\t\t<div class=\"wpb_wrapper\"><div class=\"wpb_gallery_slidesflickity_static_height_style\" data-onclick=\"link_no\" data-interval=\"5\"><style>.wpb_gallery_slidesflickity_static_height_style .nectar-flickity.instace-6a04ebf26e08d:not(.masonry) .flickity-slider .cell img {\n      height: 500px;\n    }\n    @media only screen and (max-width: 1300px) {\n      .wpb_gallery_slidesflickity_static_height_style .nectar-flickity.instace-6a04ebf26e08d:not(.masonry) .flickity-slider .cell img {\n        height: 400px;\n      }\n    }\n    @media only screen and (max-width: 1000px) {\n      .wpb_gallery_slidesflickity_static_height_style .nectar-flickity.instace-6a04ebf26e08d:not(.masonry) .flickity-slider .cell img {\n        height: 350px;\n      }\n    }\n    @media only screen and (max-width: 690px) {\n      .wpb_gallery_slidesflickity_static_height_style .nectar-flickity.instace-6a04ebf26e08d:not(.masonry) .flickity-slider .cell img {\n        height: 300px;\n      }\n    }<\/style><div class=\"nectar-flickity not-initialized instace-6a04ebf26e08d\"  data-touch-icon-color=\"default\" data-drag-scale=\"\" data-overflow=\"hidden\" data-wrap=\"wrap\" data-spacing=\"default\" data-shadow=\"large_depth\" data-autoplay=\"\" data-autoplay-dur=\"\" data-free-scroll=\"\" data-controls=\"material_pagination\"><div class=\"flickity-viewport\"> <div class=\"flickity-slider\"><div class=\"cell\" data-lazy=\"false\"><div class=\"nectar-el-parallax-scroll\" data-scroll-animation=\"true\" data-scroll-animation-mobile=\"true\" data-scroll-animation-intensity=\"-1.15\" data-scroll-animation-lerp=\"1\"><div class=\"vc_column-inner\"><div class=\"img-wrap\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/estrelasceu3-1024x683.jpeg\" class=\"skip-lazy nectar-lazy attachment-large\" alt=\"\" srcset=\"https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/estrelasceu3-1024x683.jpeg 1024w, https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/estrelasceu3-300x200.jpeg 300w, https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/estrelasceu3-768x512.jpeg 768w, https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/estrelasceu3-1536x1024.jpeg 1536w, https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/estrelasceu3-900x600.jpeg 900w, https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/estrelasceu3.jpeg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/div><\/div><div class=\"cell\" data-lazy=\"false\"><div class=\"nectar-el-parallax-scroll\" data-scroll-animation=\"true\" data-scroll-animation-mobile=\"true\" data-scroll-animation-intensity=\"-1.15\" data-scroll-animation-lerp=\"1\"><div class=\"vc_column-inner\"><div class=\"img-wrap\"><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/estrelasceu4-1024x683.jpeg\" class=\"skip-lazy nectar-lazy attachment-large\" alt=\"\" srcset=\"https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/estrelasceu4-1024x683.jpeg 1024w, https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/estrelasceu4-300x200.jpeg 300w, https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/estrelasceu4-768x512.jpeg 768w, https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/estrelasceu4-1536x1024.jpeg 1536w, https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/estrelasceu4-900x600.jpeg 900w, https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/estrelasceu4.jpeg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/div><\/div><div class=\"cell\" data-lazy=\"false\"><div class=\"nectar-el-parallax-scroll\" data-scroll-animation=\"true\" data-scroll-animation-mobile=\"true\" data-scroll-animation-intensity=\"-1.15\" data-scroll-animation-lerp=\"1\"><div class=\"vc_column-inner\"><div class=\"img-wrap\"><img decoding=\"async\" width=\"1024\" height=\"900\" src=\"https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/estrelasceu1-1024x900.jpeg\" class=\"skip-lazy nectar-lazy attachment-large\" alt=\"\" srcset=\"https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/estrelasceu1-1024x900.jpeg 1024w, https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/estrelasceu1-300x264.jpeg 300w, https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/estrelasceu1-768x675.jpeg 768w, https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/estrelasceu1-1536x1350.jpeg 1536w, https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/estrelasceu1.jpeg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/div><\/div><div class=\"cell\" data-lazy=\"false\"><div class=\"nectar-el-parallax-scroll\" data-scroll-animation=\"true\" data-scroll-animation-mobile=\"true\" data-scroll-animation-intensity=\"-1.15\" data-scroll-animation-lerp=\"1\"><div class=\"vc_column-inner\"><div class=\"img-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/estrelasceu2-1024x683.jpeg\" class=\"skip-lazy nectar-lazy attachment-large\" alt=\"\" srcset=\"https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/estrelasceu2-1024x683.jpeg 1024w, https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/estrelasceu2-300x200.jpeg 300w, https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/estrelasceu2-768x512.jpeg 768w, https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/estrelasceu2-1536x1024.jpeg 1536w, https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/estrelasceu2-900x600.jpeg 900w, https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/estrelasceu2.jpeg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n\t\t<\/div> \n\t<\/div> \n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a04ebf26e85c\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row full-width-content vc_row-o-equal-height vc_row-flex vc_row-o-content-top\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-overlay=\"false\"><div class=\"inner-wrap\"><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div id=\"fws_6a04ebf26e977\" data-midnight=\"\" data-column-margin=\"none\" class=\"wpb_row vc_row-fluid vc_row inner_row\"  style=\" z-index: 100;\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" data-scroll-animation=\"true\" data-scroll-animation-movement=\"transform_x\" data-scroll-animation-mobile=\"true\" data-scroll-animation-intensity=\"3.5\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar-scrolling-text font_size_11vw font_size_mobile_15vw\" data-style=\"text_outline\" data-s-dir=\"ltr\" data-spacing=\"false\" data-outline-thickness=\"ultra-thin\" data-s-speed=\"slowest\" data-overflow=\"visible\" ><div class=\"nectar-scrolling-text-inner\" style=\"color: #ddb06c;\">\n<h1><em>Ficha\u00a0<\/em>t\u00e9cnica<span>&nbsp;<\/span><\/h1>\n\n<h1><em>Ficha\u00a0<\/em>t\u00e9cnica<span>&nbsp;<\/span><\/h1>\n\n<h1><em>Ficha\u00a0<\/em>t\u00e9cnica<span>&nbsp;<\/span><\/h1>\n\n<h1><em>Ficha\u00a0<\/em>t\u00e9cnica<span>&nbsp;<\/span><\/h1>\n\n<h1><em>Ficha\u00a0<\/em>t\u00e9cnica<span>&nbsp;<\/span><\/h1>\n<\/div><\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a04ebf26ecf8\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-overlay=\"false\"><div class=\"inner-wrap\"><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a04ebf26eece\"  data-column-margin=\"default\" data-midnight=\"light\" data-top-percent=\"13%\" data-bottom-percent=\"12%\"  data-bg-mobile-hidden=\"true\" class=\"wpb_row vc_row-fluid vc_row full-width-section parallax_section\"  style=\"padding-top: calc(100vw * 0.13); padding-bottom: calc(100vw * 0.12); \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-overlay=\"true\"><div class=\"inner-wrap using-image\"><div class=\"row-bg viewport-desktop using-image\" data-parallax-speed=\"fast\" style=\"background-position: center top; background-repeat: no-repeat; \"><\/div><\/div><div class=\"row-bg-overlay\" style=\"background-color:#da5143;  opacity: 1; \"><\/div><\/div><div class=\"row_col_wrap_12 col span_12 light left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div id=\"fws_6a04ebf26efd0\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-3 wpb_column column_container vc_column_container col child_column centered-text no-extra-padding inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h5 style=\"color: rgba(255,255,255,0.63);text-align: center\" class=\"vc_custom_heading vc_custom_1648487690992\" >Duraci\u00f3n del Espect\u00e1culo<\/h5><div class=\"nectar-milestone\" data-symbol=\"min\" data-symbol-alignment=\"superscript\" data-symbol-pos=\"after\" data-symbol-size=\"20\" data-animation-delay=\"\" data-ms-align=\"default\" > <div class=\"number default\" data-number-size=\"92\"><h5><span>60min<\/span><\/h5><\/div> <div class=\"subject\" style=\"padding: 2%;\"><\/div> <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-3 wpb_column column_container vc_column_container col child_column centered-text no-extra-padding inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h5 style=\"color: rgba(255,255,255,0.63);text-align: center\" class=\"vc_custom_heading vc_custom_1648487630461\" >Artistas<\/h5><div class=\"nectar-milestone\"  data-animation-delay=\"\" data-ms-align=\"default\" > <div class=\"number default\" data-number-size=\"92\"><h5><span>5<\/span><\/h5><\/div> <div class=\"subject\" style=\"padding: 2%;\"><\/div> <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-3 wpb_column column_container vc_column_container col child_column centered-text no-extra-padding inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h5 style=\"color: rgba(255,255,255,0.63);text-align: center\" class=\"vc_custom_heading vc_custom_1652295841997\" >Presentaciones<\/h5><div class=\"nectar-milestone\"  data-animation-delay=\"\" data-ms-align=\"default\" > <div class=\"number default\" data-number-size=\"92\"><h5><span>15<\/span><\/h5><\/div> <div class=\"subject\" style=\"padding: 2%;\"><\/div> <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a04ebf26fba0\"  data-column-margin=\"80px\" data-midnight=\"dark\" data-top-percent=\"9%\"  class=\"wpb_row vc_row-fluid vc_row full-width-section\"  style=\"padding-top: calc(100vw * 0.09); padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-overlay=\"false\"><div class=\"inner-wrap\"><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding el_spacing_5px inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div id=\"fws_6a04ebf26fd0e\" data-midnight=\"\" data-column-margin=\"90px\" class=\"wpb_row vc_row-fluid vc_row inner_row\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-4 wpb_column column_container vc_column_container col child_column has-animation padding-3-percent inherit_tablet inherit_phone\"   data-padding-pos=\"bottom\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"fade-in-from-bottom\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<h4><b>Direcci\u00f3n, Escenograf\u00eda, Vestuario y Dramaturgia<\/b><\/h4>\n\t<\/div>\n<\/div>\n\n\n\n\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<p><span style=\"font-weight: 400;\">Ricardo Harada<\/span><\/p>\n\t<\/div>\n<\/div>\n\n\n\n\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-4 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<h4>Producci\u00f3n<\/h4>\n\t<\/div>\n<\/div>\n\n\n\n\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<p><span style=\"font-weight: 400;\">Os Geraldos<\/span><\/p>\n\t<\/div>\n<\/div>\n\n\n\n\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-4 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<h4>Arte Gr\u00e1fica<\/h4>\n\t<\/div>\n<\/div>\n\n\n\n\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<p><span style=\"font-weight: 400;\">Vanessa Cavalcanti<\/span><\/p>\n\t<\/div>\n<\/div>\n\n\n\n\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div><div id=\"fws_6a04ebf26ffd0\" data-midnight=\"\" data-column-margin=\"90px\" class=\"wpb_row vc_row-fluid vc_row inner_row\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-4 wpb_column column_container vc_column_container col child_column has-animation padding-3-percent inherit_tablet inherit_phone\"   data-padding-pos=\"bottom\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"fade-in-from-bottom\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<h4>Iluminaci\u00f3n<\/h4>\n\t<\/div>\n<\/div>\n\n\n\n\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<p><span style=\"font-weight: 400;\">Ricardo Harada e Os Geraldos<\/span><\/p>\n\t<\/div>\n<\/div>\n\n\n\n\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-4 wpb_column column_container vc_column_container col child_column has-animation no-extra-padding inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"fade-in-from-bottom\" data-delay=\"100\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<h4>T\u00e9cnico de Luz<\/h4>\n\t<\/div>\n<\/div>\n\n\n\n\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<p><span style=\"font-weight: 400;\">Jo\u00e3o Victor Fernandes<\/span><\/p>\n\t<\/div>\n<\/div>\n\n\n\n\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-4 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<h4>T\u00e9cnico de Sonido<\/h4>\n\t<\/div>\n<\/div>\n\n\n\n\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<p><span style=\"font-weight: 400;\">Paula Guerreiro<\/span><\/p>\n\t<\/div>\n<\/div>\n\n\n\n\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div><div id=\"fws_6a04ebf270224\" data-midnight=\"\" data-column-margin=\"90px\" class=\"wpb_row vc_row-fluid vc_row inner_row\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col child_column has-animation no-extra-padding inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"fade-in-from-bottom\" data-delay=\"100\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<h4>Elenco<\/h4>\n\t<\/div>\n<\/div>\n\n\n\n\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<p>Carolina Delduque, Douglas Novais, Patr\u00edcia Pala\u00e7on, Railan Andrade e Vinicius Santino<\/p>\n\t<\/div>\n<\/div>\n\n\n\n\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>","protected":false},"excerpt":{"rendered":"Sinopse Em \u201cAs Estrelas do C\u00e9u\u201d, acompanhamos as aventuras de uma menina que empreende uma jornada fant\u00e1stica em busca de seu grande sonho: tocar as estrelas do c\u00e9u. Durante sua...","protected":false},"author":1,"featured_media":66,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":{"0":"post-320","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-espetaculo"},"_links":{"self":[{"href":"https:\/\/osgeraldos.com.br\/es\/wp-json\/wp\/v2\/posts\/320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/osgeraldos.com.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/osgeraldos.com.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/osgeraldos.com.br\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/osgeraldos.com.br\/es\/wp-json\/wp\/v2\/comments?post=320"}],"version-history":[{"count":9,"href":"https:\/\/osgeraldos.com.br\/es\/wp-json\/wp\/v2\/posts\/320\/revisions"}],"predecessor-version":[{"id":727,"href":"https:\/\/osgeraldos.com.br\/es\/wp-json\/wp\/v2\/posts\/320\/revisions\/727"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/osgeraldos.com.br\/es\/wp-json\/wp\/v2\/media\/66"}],"wp:attachment":[{"href":"https:\/\/osgeraldos.com.br\/es\/wp-json\/wp\/v2\/media?parent=320"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/osgeraldos.com.br\/es\/wp-json\/wp\/v2\/categories?post=320"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/osgeraldos.com.br\/es\/wp-json\/wp\/v2\/tags?post=320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}