{"id":21,"date":"2022-03-24T01:54:08","date_gmt":"2022-03-24T01:54:08","guid":{"rendered":"https:\/\/osgeraldos.com.br\/?p=21"},"modified":"2023-12-30T18:18:25","modified_gmt":"2023-12-30T18:18:25","slug":"formacao-1","status":"publish","type":"post","link":"https:\/\/osgeraldos.com.br\/en\/formacao-1\/","title":{"rendered":"Transformations"},"content":{"rendered":"<div id=\"fws_6a04ec94b00e4\"  data-column-margin=\"default\" data-midnight=\"dark\" data-top-percent=\"5%\" data-bottom-percent=\"7%\"  class=\"wpb_row vc_row-fluid vc_row full-width-section\"  style=\"padding-top: calc(100vw * 0.05); padding-bottom: calc(100vw * 0.07); \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-overlay=\"false\"><div class=\"inner-wrap\"><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col centered-text no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div id=\"fws_6a04ec94b02b2\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col child_column has-animation padding-3-percent inherit_tablet inherit_phone\"   data-padding-pos=\"top-bottom\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"fade-in-from-bottom\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n<div class=\"wpb_text_column wpb_content_element  vc_custom_1703958872143\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<p style=\"text-align: center;\" class=\"translation-block\">Transformations is a project carried out by the group since 2012, working as an Oriented Internship Program that has welcomed over 60 young participants. The action corresponds to a training in the field of cultural management, by connecting learning and doing, student activity and professional realization. Participants immerse themselves in the daily life of the Os Geraldos group and the Theater Art and Craft\u2019s activities,with experiences related to Cultural Management. - management, maintenance and production of the group's artistic, formative and headquarters projects - and artistic creation - actively participating in the activities of the Visualities Workshop and the processes of staging and circulating shows. They take on practical roles, contributing to the technical and production aspects involved. At the end of the project, a serie of evaluations are carried out. Participants engage in discussions with their supervisors, reflecting on their individual journeys and evolution as artists.<\/p>\n\t<\/div>\n<\/div>\n\n\n\n\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a04ec94b0462\"  data-column-margin=\"default\" data-midnight=\"dark\" data-bottom-percent=\"7%\"  class=\"wpb_row vc_row-fluid vc_row full-width-content vc_row-o-equal-height vc_row-flex vc_row-o-content-top\"  style=\"padding-top: 0px; padding-bottom: calc(100vw * 0.07); \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-overlay=\"false\"><div class=\"inner-wrap\"><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t<div class=\"wpb_gallery wpb_content_element clearfix\">\n\t\t<div class=\"wpb_wrapper\"><div class=\"wpb_gallery_slidesflickity_static_height_style\" data-onclick=\"link_no\" data-interval=\"5\"><style>.wpb_gallery_slidesflickity_static_height_style .nectar-flickity.instace-6a04ec94b052d:not(.masonry) .flickity-slider .cell img {\n      height: 400px;\n    }\n    @media only screen and (max-width: 1300px) {\n      .wpb_gallery_slidesflickity_static_height_style .nectar-flickity.instace-6a04ec94b052d:not(.masonry) .flickity-slider .cell img {\n        height: 400px;\n      }\n    }\n    @media only screen and (max-width: 1000px) {\n      .wpb_gallery_slidesflickity_static_height_style .nectar-flickity.instace-6a04ec94b052d:not(.masonry) .flickity-slider .cell img {\n        height: 350px;\n      }\n    }\n    @media only screen and (max-width: 690px) {\n      .wpb_gallery_slidesflickity_static_height_style .nectar-flickity.instace-6a04ec94b052d:not(.masonry) .flickity-slider .cell img {\n        height: 300px;\n      }\n    }<\/style><div class=\"nectar-flickity not-initialized instace-6a04ec94b052d\"  data-touch-icon-color=\"default\" data-drag-scale=\"\" data-overflow=\"hidden\" data-wrap=\"wrap\" data-spacing=\"default\" data-shadow=\"large_depth\" data-autoplay=\"\" data-autoplay-dur=\"\" data-free-scroll=\"\" data-controls=\"material_pagination\"><div class=\"flickity-viewport\"> <div class=\"flickity-slider\"><div class=\"cell\" data-lazy=\"false\"><img fetchpriority=\"high\" decoding=\"async\" width=\"716\" height=\"537\" src=\"https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/cf2018-6.jpeg\" class=\"skip-lazy nectar-lazy attachment-large\" alt=\"\" srcset=\"https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/cf2018-6.jpeg 716w, https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/cf2018-6-300x225.jpeg 300w\" sizes=\"(max-width: 716px) 100vw, 716px\" \/><\/div><div class=\"cell\" data-lazy=\"false\"><img decoding=\"async\" width=\"759\" height=\"569\" src=\"https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/cf2018-4.jpeg\" class=\"skip-lazy nectar-lazy attachment-large\" alt=\"\" srcset=\"https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/cf2018-4.jpeg 759w, https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/cf2018-4-300x225.jpeg 300w\" sizes=\"(max-width: 759px) 100vw, 759px\" \/><\/div><div class=\"cell\" data-lazy=\"false\"><img decoding=\"async\" width=\"433\" height=\"577\" src=\"https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/cf2018-2.jpeg\" class=\"skip-lazy nectar-lazy attachment-large\" alt=\"\" srcset=\"https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/cf2018-2.jpeg 433w, https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/cf2018-2-225x300.jpeg 225w\" sizes=\"(max-width: 433px) 100vw, 433px\" \/><\/div><div class=\"cell\" data-lazy=\"false\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/IMG_0068-1024x683.jpg\" class=\"skip-lazy nectar-lazy attachment-large\" alt=\"\" srcset=\"https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/IMG_0068-1024x683.jpg 1024w, https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/IMG_0068-300x200.jpg 300w, https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/IMG_0068-768x512.jpg 768w, https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/IMG_0068-1536x1024.jpg 1536w, https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/IMG_0068-2048x1365.jpg 2048w, https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/IMG_0068-18x12.jpg 18w, https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/IMG_0068-900x600.jpg 900w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/div><div class=\"cell\" data-lazy=\"false\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/IMG_0573-1024x683.jpg\" class=\"skip-lazy nectar-lazy attachment-large\" alt=\"\" srcset=\"https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/IMG_0573-1024x683.jpg 1024w, https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/IMG_0573-300x200.jpg 300w, https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/IMG_0573-768x512.jpg 768w, https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/IMG_0573-1536x1024.jpg 1536w, https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/IMG_0573-2048x1365.jpg 2048w, https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/IMG_0573-18x12.jpg 18w, https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/IMG_0573-900x600.jpg 900w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/div><div class=\"cell\" data-lazy=\"false\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"580\" src=\"https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/Screen-Shot-2023-12-22-at-18.39.42-1024x580.png\" class=\"skip-lazy nectar-lazy attachment-large\" alt=\"\" srcset=\"https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/Screen-Shot-2023-12-22-at-18.39.42-1024x580.png 1024w, https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/Screen-Shot-2023-12-22-at-18.39.42-300x170.png 300w, https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/Screen-Shot-2023-12-22-at-18.39.42-768x435.png 768w, https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/Screen-Shot-2023-12-22-at-18.39.42-1536x870.png 1536w, https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/Screen-Shot-2023-12-22-at-18.39.42-2048x1160.png 2048w, https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/Screen-Shot-2023-12-22-at-18.39.42-18x10.png 18w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/div><div class=\"cell\" data-lazy=\"false\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/IMG_0078-1024x683.jpg\" class=\"skip-lazy nectar-lazy attachment-large\" alt=\"\" srcset=\"https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/IMG_0078-1024x683.jpg 1024w, https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/IMG_0078-300x200.jpg 300w, https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/IMG_0078-768x512.jpg 768w, https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/IMG_0078-1536x1024.jpg 1536w, https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/IMG_0078-2048x1365.jpg 2048w, https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/IMG_0078-18x12.jpg 18w, https:\/\/osgeraldos.com.br\/wp-content\/uploads\/2022\/03\/IMG_0078-900x600.jpg 900w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/div><\/div><\/div>\n\t\t<\/div> \n\t<\/div> \n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>","protected":false},"excerpt":{"rendered":"Transforma\u00e7\u00f5es apresenta-se como um projeto realizado pelo grupo desde 2012, que funciona como um Programa de Est\u00e1gio Orientado, que j\u00e1 recebeu mais de 65 jovens. A a\u00e7\u00e3o corresponde a uma...","protected":false},"author":1,"featured_media":845,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":{"0":"post-21","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-formacao"},"_links":{"self":[{"href":"https:\/\/osgeraldos.com.br\/en\/wp-json\/wp\/v2\/posts\/21","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/osgeraldos.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/osgeraldos.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/osgeraldos.com.br\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/osgeraldos.com.br\/en\/wp-json\/wp\/v2\/comments?post=21"}],"version-history":[{"count":30,"href":"https:\/\/osgeraldos.com.br\/en\/wp-json\/wp\/v2\/posts\/21\/revisions"}],"predecessor-version":[{"id":850,"href":"https:\/\/osgeraldos.com.br\/en\/wp-json\/wp\/v2\/posts\/21\/revisions\/850"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/osgeraldos.com.br\/en\/wp-json\/wp\/v2\/media\/845"}],"wp:attachment":[{"href":"https:\/\/osgeraldos.com.br\/en\/wp-json\/wp\/v2\/media?parent=21"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/osgeraldos.com.br\/en\/wp-json\/wp\/v2\/categories?post=21"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/osgeraldos.com.br\/en\/wp-json\/wp\/v2\/tags?post=21"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}